{"id":2623,"date":"2018-02-05T00:37:38","date_gmt":"2018-02-04T23:37:38","guid":{"rendered":"https:\/\/www.altimara.eu\/blog\/?p=2623"},"modified":"2018-02-05T00:37:38","modified_gmt":"2018-02-04T23:37:38","slug":"lupin-islande","status":"publish","type":"post","link":"https:\/\/www.altimara.eu\/blog\/2018\/02\/05\/lupin-islande\/","title":{"rendered":"Lupin Islande"},"content":{"rendered":"<p>Un petit s\u00e9jour en Islande, les aurores bor\u00e9ales sont plus que rares, faut dire que le ciel ne s&rsquo;y pr\u00eate pas. Neige, temp\u00eate, pluie verglac\u00e9e, l&rsquo;azur est plut\u00f4t sombre.<\/p>\n<p>J&rsquo;en profite pour rester au chaud dans l&rsquo;atelier est transformer le petit baril du four \u00e0 carboniser. J&rsquo;ai apport\u00e9 des tuyaux de cuivre de 18 et des manchons et coudes \u00e0 olives. En Islande le cuivre est peu utilis\u00e9 en plomberie, c&rsquo;est pour \u00e7a que l&rsquo;\u00e9t\u00e9 dernier j&rsquo;avais eu des difficult\u00e9s pour fabriquer le tuyau \u00ab\u00a0gazog\u00e8ne\u00a0\u00bb. Le remplacement parait superbe et l&rsquo;augmentation du diam\u00e8tre du tuyau va donner plus de gaz donc plus de combustion sous le baril.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2625\" data-permalink=\"https:\/\/www.altimara.eu\/blog\/2018\/02\/05\/lupin-islande\/img_20180204_183037215\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215.jpg?fit=1000%2C563&amp;ssl=1\" data-orig-size=\"1000,563\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;MotoG3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1517769038&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.64&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_20180204_183037215\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215.jpg?fit=627%2C353&amp;ssl=1\" class=\"aligncenter size-medium wp-image-2625\" src=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215-300x169.jpg?resize=300%2C169\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_183037215.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Dehors les lupins font grise mine, tout secs (sous le pluie&#8230;). Ce serai la bonne p\u00e9riode pour les r\u00e9colter mais il faudrait un lieu de stockage pour \u00e7a.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2626\" data-permalink=\"https:\/\/www.altimara.eu\/blog\/2018\/02\/05\/lupin-islande\/img_20180204_150105408\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?fit=1000%2C563&amp;ssl=1\" data-orig-size=\"1000,563\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;MotoG3&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1517756465&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.64&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_20180204_150105408\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?fit=627%2C353&amp;ssl=1\" class=\"aligncenter size-full wp-image-2626\" src=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?resize=627%2C353\" alt=\"\" width=\"627\" height=\"353\" srcset=\"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2018\/02\/IMG_20180204_150105408.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/p>\n<p>On verra \u00e7a cet \u00e9t\u00e9.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un petit s\u00e9jour en Islande, les aurores bor\u00e9ales sont plus que rares, faut dire que le ciel ne s&rsquo;y pr\u00eate pas. Neige, temp\u00eate, pluie verglac\u00e9e, l&rsquo;azur est plut\u00f4t sombre. J&rsquo;en profite pour rester au chaud dans l&rsquo;atelier est transformer le petit baril du four \u00e0 carboniser. J&rsquo;ai apport\u00e9 des tuyaux de cuivre de 18 et [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[86,110],"tags":[91,104,33,92],"class_list":["post-2623","post","type-post","status-publish","format-standard","hentry","category-charbon-vegetal","category-ecochar","tag-charbon-vegetal","tag-ecochar","tag-islande","tag-lupin"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4r91c-Gj","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2426,"url":"https:\/\/www.altimara.eu\/blog\/2017\/08\/21\/lupin-ecochar-6\/","url_meta":{"origin":2623,"position":0},"title":"Lupin \u00e9cochar","author":"Martiou","date":"21 ao\u00fbt 2017","format":false,"excerpt":"Construction du four. J'ai enfin r\u00e9cup\u00e9r\u00e9 le petit fut de 55l, indispensable pour carboniser les lupins. C'est \u00e0 gr\u00e2ce \u00e0 Gummi, mon sympathique conducteur sur un circuit et qui travaille aussi dans la compagnie \"Olis\", que LE fut islandais de ce volume a \u00e9t\u00e9 trouv\u00e9. Aussit\u00f4t arriv\u00e9 \u00e0 Reykjavik, j'ai\u2026","rel":"","context":"Dans &quot;3 Charbon de bois Islande&quot;","block_context":{"text":"3 Charbon de bois Islande","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-de-bois-islande\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/08\/20170820_131003-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2391,"url":"https:\/\/www.altimara.eu\/blog\/2017\/07\/27\/lupin-ecochar-5\/","url_meta":{"origin":2623,"position":1},"title":"Lupin \u00e9cochar","author":"Martiou","date":"27 juillet 2017","format":false,"excerpt":"Je suis en face d'un probl\u00e8me dont je n'avais pas anticip\u00e9 la difficult\u00e9 dans la belle Islande: il est quasiment impossible de trouver un f\u00fbt m\u00e9tallique de 60 l. Pour terminer la construction du four je dois donc trouver une solution de remplacement. Est-ce possible avec une bouteille de gaz?\u2026","rel":"","context":"Dans &quot;3 Charbon de bois Islande&quot;","block_context":{"text":"3 Charbon de bois Islande","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-de-bois-islande\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/20170727_194639-e1501193921565.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":4460,"url":"https:\/\/www.altimara.eu\/blog\/2024\/09\/02\/lupin-is-5\/","url_meta":{"origin":2623,"position":2},"title":"Lupin.is-5","author":"Martiou","date":"2 septembre 2024","format":false,"excerpt":"C'est l'heure du grand exercice de la carbonisation, le four va-t-il fonctionner comme esp\u00e9r\u00e9 !! Pr\u00e9paration avec d\u00e9coupe du bois flott\u00e9. Les fermiers poss\u00e8dent plusieurs km de plage noire o\u00f9 les arbres provenant soit de Sib\u00e9rie, soit du golfe du Mexique s'\u00e9chouent en quantit\u00e9. Ce bois a \u00e9t\u00e9 une ressource\u2026","rel":"","context":"Dans &quot;Bois d'Islande, bois flott\u00e9, bois plant\u00e9&quot;","block_context":{"text":"Bois d'Islande, bois flott\u00e9, bois plant\u00e9","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-de-bois-islande\/bois-dislande-bois-flotte-bois-plante\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/09\/MA5_4778.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2450,"url":"https:\/\/www.altimara.eu\/blog\/2017\/09\/02\/ecochar-lupin-islande\/","url_meta":{"origin":2623,"position":3},"title":"\u00c9cochar lupin Islande","author":"Martiou","date":"2 septembre 2017","format":false,"excerpt":"Mise en fonctionnement du four \u00e0 lupin. Tout d'abord j'ai pos\u00e9 l'isolant, de la laine de roche de r\u00e9cup\u00e9ration, entre les deux grands tonneaux. Puis rempli le petit tonneau de 14 kg de lupins qui se r\u00e9v\u00e9l\u00e8ront beaucoup trop mouill\u00e9s pour une bonne carbonisation.\u00a0 Le four fonctionne tr\u00e8s bien. L'\u00e9tanch\u00e9it\u00e9\u2026","rel":"","context":"Dans &quot;Charbon v\u00e9g\u00e9tal&quot;","block_context":{"text":"Charbon v\u00e9g\u00e9tal","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-vegetal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/09\/20170902_105016-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2355,"url":"https:\/\/www.altimara.eu\/blog\/2017\/07\/04\/lupin-ecochar\/","url_meta":{"origin":2623,"position":4},"title":"Lupin \u00e9cochar","author":"Martiou","date":"4 juillet 2017","format":false,"excerpt":"L\u00fap\u00edna l\u00fdst \u00fatl\u00e6g \u00far vistkerfi Austfjar\u00f0a me\u00f0 hj\u00e1lp \u00edb\u00faa La lutte contre l'envahissement des lupins se d\u00e9veloppe. Un article du journal \"Frettabla\u00f0i\u00f0\" parle de l'action d'un environnementaliste islandaise, Anna Berg, qui demande \u00e0 la population de passer \u00e0 l'action contre les lupins. Les lupins, plantes invasives, d\u00e9truisent l'\u00e9cosyst\u00e8me original. Les\u2026","rel":"","context":"Dans &quot;3 Charbon de bois Islande&quot;","block_context":{"text":"3 Charbon de bois Islande","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-de-bois-islande\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/article-lupin-1024x976.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/article-lupin-1024x976.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2017\/07\/article-lupin-1024x976.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":4391,"url":"https:\/\/www.altimara.eu\/blog\/2024\/06\/26\/charbon-vegetal-islande\/","url_meta":{"origin":2623,"position":5},"title":"Charbon v\u00e9g\u00e9tal Islande","author":"Martiou","date":"26 juin 2024","format":false,"excerpt":"Le mois d'aout va \u00eatre intense pour la fabrication de briquettes de charbon \u00e0 base de lupins. Le lupin est une plante import\u00e9e d'Alaska qui a la propri\u00e9t\u00e9 de fixer les sols meubles comme les vastes \u00e9tendues des \"sandar\" islandais (Un sandur, au pluriel sandar, est en g\u00e9ologie une plaine\u2026","rel":"","context":"Dans &quot;3 Charbon de bois Islande&quot;","block_context":{"text":"3 Charbon de bois Islande","link":"https:\/\/www.altimara.eu\/blog\/category\/charbon-de-bois-islande\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.altimara.eu\/blog\/wp-content\/uploads\/2024\/06\/IMG_20240622_141256-copie.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/posts\/2623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/comments?post=2623"}],"version-history":[{"count":0,"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/posts\/2623\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/media?parent=2623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/categories?post=2623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altimara.eu\/blog\/wp-json\/wp\/v2\/tags?post=2623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}